{"id":485,"count":1,"description":"","link":"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/","name":"presenter till l\u00e4rare","slug":"presenter-till-larare","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>presenter till l\u00e4rare Archives - Dela presentid\u00e9er f\u00f6r att underl\u00e4tta din presentink\u00f6p<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"presenter till l\u00e4rare Archives - Dela presentid\u00e9er f\u00f6r att underl\u00e4tta din presentink\u00f6p\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/\" \/>\n<meta property=\"og:site_name\" content=\"Dela presentid\u00e9er f\u00f6r att underl\u00e4tta din presentink\u00f6p\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/\",\"url\":\"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/\",\"name\":\"presenter till l\u00e4rare Archives - Dela presentid\u00e9er f\u00f6r att underl\u00e4tta din presentink\u00f6p\",\"isPartOf\":{\"@id\":\"https:\/\/www.callie.se\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.callie.se\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"presenter till l\u00e4rare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.callie.se\/blog\/#website\",\"url\":\"https:\/\/www.callie.se\/blog\/\",\"name\":\"Dela presentid\u00e9er f\u00f6r att underl\u00e4tta din presentink\u00f6p\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.callie.se\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"presenter till l\u00e4rare Archives - Dela presentid\u00e9er f\u00f6r att underl\u00e4tta din presentink\u00f6p","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/","og_locale":"en_US","og_type":"article","og_title":"presenter till l\u00e4rare Archives - Dela presentid\u00e9er f\u00f6r att underl\u00e4tta din presentink\u00f6p","og_url":"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/","og_site_name":"Dela presentid\u00e9er f\u00f6r att underl\u00e4tta din presentink\u00f6p","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/","url":"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/","name":"presenter till l\u00e4rare Archives - Dela presentid\u00e9er f\u00f6r att underl\u00e4tta din presentink\u00f6p","isPartOf":{"@id":"https:\/\/www.callie.se\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.callie.se\/blog\/tag\/presenter-till-larare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.callie.se\/blog\/"},{"@type":"ListItem","position":2,"name":"presenter till l\u00e4rare"}]},{"@type":"WebSite","@id":"https:\/\/www.callie.se\/blog\/#website","url":"https:\/\/www.callie.se\/blog\/","name":"Dela presentid\u00e9er f\u00f6r att underl\u00e4tta din presentink\u00f6p","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.callie.se\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.callie.se\/blog\/wp-json\/wp\/v2\/tags\/485"}],"collection":[{"href":"https:\/\/www.callie.se\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.callie.se\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.callie.se\/blog\/wp-json\/wp\/v2\/posts?tags=485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}